{"id":477447,"count":3,"description":"","link":"https:\/\/goldisgood.com\/it\/product-category\/quartz-glass-products\/","name":"Quartz glass products","slug":"quartz-glass-products","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/goldisgood.com\/it\/wp-json\/wp\/v2\/product_cat\/477447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goldisgood.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/goldisgood.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/goldisgood.com\/it\/wp-json\/wp\/v2\/product?product_cat=477447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}